{"id":41,"count":2,"description":"","link":"https:\/\/wolu20medicalcenter.be\/fr\/specialisations\/soins-des-pieds\/","name":"Soins des pieds","slug":"soins-des-pieds","taxonomy":"specialisations","parent":28,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/wolu20medicalcenter.be\/fr\/wp-json\/wp\/v2\/specialisations\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wolu20medicalcenter.be\/fr\/wp-json\/wp\/v2\/specialisations"}],"about":[{"href":"https:\/\/wolu20medicalcenter.be\/fr\/wp-json\/wp\/v2\/taxonomies\/specialisations"}],"up":[{"embeddable":true,"href":"https:\/\/wolu20medicalcenter.be\/fr\/wp-json\/wp\/v2\/specialisations\/28"}],"wp:post_type":[{"href":"https:\/\/wolu20medicalcenter.be\/fr\/wp-json\/wp\/v2\/equipe_medicale?specialisations=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}